{"id":15452,"date":"2020-03-20T12:45:19","date_gmt":"2020-03-20T11:45:19","guid":{"rendered":"https:\/\/bernstein-bank.com\/?p=15452\/"},"modified":"2020-03-20T12:45:19","modified_gmt":"2020-03-20T11:45:19","slug":"dax-erobert-die-9-000-zurueck","status":"publish","type":"post","link":"https:\/\/bernstein-bank.com\/de\/dax-erobert-die-9-000-zurueck\/","title":{"rendered":"DAX erobert die 9.000 zur\u00fcck"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8573 aligncenter\" src=\"\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg\" width=\"602\" height=\"403\" \/><\/p>\n<p align=\"justify\"><strong>20.03.2020 \u2013Daily Report.<\/strong> <strong>Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf. Die US-Futures steigen wegen der Aussicht auf ein entschlossenes Handeln in den USA \u2013 hier d\u00fcrfte es in K\u00fcrze Helicopter Money regnen. Zudem wird Deutschland offenbar einen neuen Schutzschirm f\u00fcr Firmen aufspannen. <\/strong><\/p>\n<h2><strong>DAX pr\u00e4sentiert sich stark<\/strong><\/h2>\n<p align=\"justify\">Der deutsche Leitindex zog 5,3 Prozent an auf 9.066 Punkte. Wir sind gespannt, wie sich der Hexensabbat heute auf die Kurse auswirkt. Tags zuvor hatte der Indikator zur Abwechslung mal wieder Kursbewegungen wie zu normalen Zeiten pr\u00e4sentiert. Der DAX schloss mit einem Plus von 2 Prozent bei 8.610 Punkten. Allerdings hatte nicht die Bazooka der Europ\u00e4ischen Zentralbank diese Erholung ausgel\u00f6st \u2013 sondern der Schwenk gen Norden an der Wall Street. Die US-Futures zogen zuletzt um \u00fcber 5 Prozent an.<\/p>\n<h2><strong>Fonds \u00fcber 500 Milliarden Euro f\u00fcr deutsche Firmen<\/strong><\/h2>\n<p align=\"justify\">Einer der Gr\u00fcnde f\u00fcr die gute Laune: Wie \u201eDer Spiegel\u201c meldete, will die Bundesregierung einen neuen Rettungsschirm f\u00fcr Unternehmen aufspannen, die wegen Corona in Not geraten sind. Der Fonds soll ein Volumen von rund 500 Milliarden Euro enthalten. Damit sollen Firmen vor der Insolvenz gerettet werden, indem der Fonds Garantien f\u00fcr Verbindlichkeiten ausspricht oder tats\u00e4chlich Kapital zuschie\u00dft. Dies laufe wohl auf eine Teilverstaatlichung hinaus. Vorbild daf\u00fcr sei der Sonderfonds Finanzmarktstabilisierung (Soffin), mit dem der Staat w\u00e4hrend der Finanzkrise vor zw\u00f6lf Jahren Banken vor der Schieflage gerettet hatte \u2013 er war damals mit 480 Milliarden Euro ausgestattet, der gr\u00f6\u00dfte Teil davon Garantien. Sollten Banken in der aktuellen Krise ins Wanken geraten, will die Bundesregierung ferner den Soffin wiederbeleben.<\/p>\n<h2><strong>Bald regnet es Geld<br \/>\n<\/strong><\/h2>\n<p align=\"justify\">Noch weiter gehen die USA mit einem echten Novum: Die Menschen dort d\u00fcrften in K\u00fcrze einen Scheck von der Regierung erhalten. Treasury Secretary Steven Mnuchin nannte dem Fox Business Network Details zum Helikopter-Geld: Insgesamt sollen in zwei Tranchen 500 Milliarden Dollar direkt an die Amerikaner \u00fcberwiesen werden. In der ersten Sendung sollen es 1.000 Dollar pro Erwachsenen und 500 Dollar pro Kind sein. Satte 3.000 Dollar also f\u00fcr eine vierk\u00f6pfige Familie. Und gestern reichte der republikanische Mehrheitsf\u00fchrer Mitch McConnell einen \u00e4hnlichen Stimulus-Vorschlag ein, der nun mit den Democrats verhandelt werden soll.<br \/>\nEin fulminanter Marshall-Plan also an den Banken vorbei, die Staatsst\u00fctze h\u00e4ufig zur eigenen Stabilisierung verwenden. Analog dazu betonte US-Pr\u00e4sident Donald Trump gestern auf seiner Pressekonferenz: Konzerne, bei denen der Staat zur Rettung einsteigt und Anteile \u00fcbernimmt, d\u00fcrften sich weder Aktien-R\u00fcckk\u00e4ufe mit dem Steuergeld leisten oder gar die Boni f\u00fcr das Management erh\u00f6hen. Das ist doch mal eine Ansage.<\/p>\n<h2><strong>Leichtes Plus an der chinesischen B\u00f6rse<\/strong><\/h2>\n<p align=\"justify\">In China blieben die Anleger am Freitag noch skeptisch. So berichtete Peking erneut, dass es keine neuen Infektionen im Inland gegeben habe. Die regimekritische \u201eEpoch Times\u201c, die in der Volksrepublik bestens vernetzt ist, meldete allerdings, die Realit\u00e4t im Lande sehe anders aus. So meldeten die Quellen des Blattes lange Schlange vor Krankenh\u00e4usern, den Aufbau von Not-Hospit\u00e4lern und scharf kontrollierte Quarant\u00e4ne. An der B\u00f6rse sorgte neben Corona auch die Tatsache f\u00fcr Zur\u00fcckhaltung, dass die People&#8217;s Bank of China (PBoC) auf eine Zinssenkung verzichtet hat. Immerhin gewann der CSI-300 um 1,8 Prozent auf 3.653 Stellen. In Tokio blieb die B\u00f6rse wegen des Feiertags zum Fr\u00fchlingsanfang geschlossen.<\/p>\n<h2><strong>New York k\u00e4mpft sich nach oben<\/strong><\/h2>\n<p align=\"justify\">Signale der Stabilisierung hatte am gestrigen Donnerstag schon die Wall Street ausgesandt. Der Index schloss rund 1 Prozent h\u00f6her bei 20.087 Punkten. Dabei war er im fr\u00fchen Handel um mehr als 3,5 Prozent gerutscht, zwischenzeitlich war er aber auch um fast 3 Prozent geklettert. Der Nasdaq 100 gewann 1,6 Prozent auf 7.289 Stellen. Und der S&amp;P 500 legte zum Schluss 0,5 Prozent auf 2.409 Punkte zu. Der kr\u00e4ftige Einbruch im Philly-Fed-Index und das Minus der US-Leistungsbilanz waren erwartet worden. Genau wie der starke Anstieg in der Zahl der Erstantr\u00e4ge auf Arbeitslosenhilfe. Wir sind also gespannt, ob die Wall Street angesichts all der oben beschriebenen eingeleiteten Schritte nun eine kr\u00e4ftige Erholung einleitet.<\/p>\n<h2><strong>Rekord-Tag f\u00fcr Erd\u00f6l<\/strong><\/h2>\n<p align=\"justify\">Diese Erholung erlebte der \u00d6lmarkt gestern: Erd\u00f6l legte den gr\u00f6\u00dften Tagesgewinn aller Zeiten vor. So zog WTI zwischenzeitlich um 26 Prozent an. Zuletzt legte WTI um 9,3 Prozent zu auf 28,31 Dollar und Brent verteuerte sich um 7,8 Prozent auf 32,65 Dollar. Zur Eind\u00e4mmung der \u00d6lflut will Texas nun offenbar die F\u00f6rderung kappen, wie das \u201eWall Street Journal\u201c unter Berufung auf Insider berichtet. Dies w\u00e4re das erste Mal seit dem \u00d6lschock in den Siebzigern. Weiter h\u00e4tten Top-Manager der Industrie den f\u00fcr die Branche zust\u00e4ndigen Regulierer, die Texas Railroad Commission, um staatliche Hilfe gebeten. Das zeigt: Die US-\u00d6lbranche steht mit dem R\u00fccken zur Wand. Gehen Sie davon aus, dass ein Gro\u00dfteil der kleinen F\u00f6rderer umkippt \u2013 was das Angebot verknappt.<\/p>\n<h2><strong>Das bringt der Tag<br \/>\n<\/strong><\/h2>\n<p align=\"justify\">Zum Weekend ist von der Terminlage her Entspannung angesagt. Den \u00dcberblick finden Sie wie immer hier: <strong><a href=\"https:\/\/bernstein-bank.com\/de\/research\/#market-mover\">Market Mover<\/a><\/strong><\/p>\n<p>Allenfalls die Verk\u00e4ufe von gebrauchten Immobilien in den USA im Februar um 15.00 Uhr k\u00f6nnten auf ein wenig Interesse an der Wall Street sto\u00dfen.<\/p>\n<p>Die Bernstein-Bank w\u00fcnscht erfolgreiche Trades \u2013 und viel Sonne zum Angrillen in der h\u00e4uslichen Quarant\u00e4ne!<\/p>\n<hr \/>\n<p style=\"text-align: center;\">Wichtige Hinweise:<\/p>\n<p align=\"justify\"><small> Der Inhalt dieser Publikation dient ausschlie\u00dflich allgemeinen Informationszwecken. Es handelt sich in diesem Kontext weder um eine individuelle Anlageempfehlung oder -beratung, noch um ein Angebot zum Erwerb oder der Ver\u00e4u\u00dferung von Wertpapieren oder anderen Finanzprodukten. Der betreffende Inhalt sowie s\u00e4mtliche enthaltenen Informationen ersetzen in keiner Weise eine individuelle anleger- bzw. anlagegerechte Beratung. Jegliche Darstellungen oder Angaben zu gegenwertigen oder vergangenen Wertentwicklungen der betreffenden Basiswerte erlauben keine verl\u00e4ssliche Prognose oder Indikation f\u00fcr die Zukunft. S\u00e4mtliche aufgef\u00fchrte Informationen und Daten dieser Publikation basieren auf zuverl\u00e4ssigen Quellen. Die Bernstein Bank \u00fcbernimmt jedoch keine Gew\u00e4hr bez\u00fcglich der Aktualit\u00e4t, Korrektheit und Vollst\u00e4ndigkeit der in dieser Ver\u00f6ffentlichung aufgef\u00fchrten Informationen und Daten. An den Finanzm\u00e4rkten gehandelte Wertpapiere unterliegen Kursschwankungen. Ein Contract for Difference (CFD) stellt dar\u00fcber hinaus ein Finanzinstrument mit Hebelwirkung dar. Der CFD-Handel beinhaltet vor diesem Hintergrund ein hohes Risiko bis zum Totalverlust und ist damit unter Umst\u00e4nden nicht f\u00fcr jeden Anleger geeignet. Stellen Sie deshalb sicher, dass Sie alle korrelierenden Risiken vollst\u00e4ndig verstanden haben. Lassen Sie sich gegebenenfalls von unabh\u00e4ngiger Seite beraten.<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>20.03.2020 \u2013Daily Report. Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf. Die US-Futures steigen wegen&#8230;<\/p>\n","protected":false},"author":37,"featured_media":14722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAX erobert die 9.000 zur\u00fcck | Bernstein Bank<\/title>\n<meta name=\"description\" content=\"Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAX erobert die 9.000 zur\u00fcck | Bernstein Bank\" \/>\n<meta property=\"og:description\" content=\"Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/\" \/>\n<meta property=\"og:site_name\" content=\"Bernstein Bank\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T11:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wordpress Support\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wordpress Support\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/\"},\"author\":{\"name\":\"Wordpress Support\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/#\\\/schema\\\/person\\\/f2be4e4423d78d9d97bf1e9a8db9fd48\"},\"headline\":\"DAX erobert die 9.000 zur\u00fcck\",\"datePublished\":\"2020-03-20T11:45:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/\"},\"wordCount\":1059,\"image\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bernstein-bank.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/trading-pen.jpg\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/\",\"url\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/\",\"name\":\"DAX erobert die 9.000 zur\u00fcck | Bernstein Bank\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bernstein-bank.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/trading-pen.jpg\",\"datePublished\":\"2020-03-20T11:45:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/#\\\/schema\\\/person\\\/f2be4e4423d78d9d97bf1e9a8db9fd48\"},\"description\":\"Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bernstein-bank.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/trading-pen.jpg\",\"contentUrl\":\"https:\\\/\\\/bernstein-bank.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/trading-pen.jpg\",\"width\":800,\"height\":455,\"caption\":\"Trading pen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/dax-recaptures-the-9000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bernstein-bank.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAX erobert die 9.000 zur\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/\",\"name\":\"Bernstein Bank\",\"description\":\"Bernstein Bank\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bernstein-bank.com\\\/en\\\/#\\\/schema\\\/person\\\/f2be4e4423d78d9d97bf1e9a8db9fd48\",\"name\":\"Wordpress Support\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAX erobert die 9.000 zur\u00fcck | Bernstein Bank","description":"Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/","og_locale":"de_DE","og_type":"article","og_title":"DAX erobert die 9.000 zur\u00fcck | Bernstein Bank","og_description":"Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf.","og_url":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/","og_site_name":"Bernstein Bank","article_published_time":"2020-03-20T11:45:19+00:00","og_image":[{"width":800,"height":455,"url":"https:\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg","type":"image\/jpeg"}],"author":"Wordpress Support","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wordpress Support","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#article","isPartOf":{"@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/"},"author":{"name":"Wordpress Support","@id":"https:\/\/bernstein-bank.com\/en\/#\/schema\/person\/f2be4e4423d78d9d97bf1e9a8db9fd48"},"headline":"DAX erobert die 9.000 zur\u00fcck","datePublished":"2020-03-20T11:45:19+00:00","mainEntityOfPage":{"@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/"},"wordCount":1059,"image":{"@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#primaryimage"},"thumbnailUrl":"https:\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg","articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/","url":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/","name":"DAX erobert die 9.000 zur\u00fcck | Bernstein Bank","isPartOf":{"@id":"https:\/\/bernstein-bank.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#primaryimage"},"image":{"@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#primaryimage"},"thumbnailUrl":"https:\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg","datePublished":"2020-03-20T11:45:19+00:00","author":{"@id":"https:\/\/bernstein-bank.com\/en\/#\/schema\/person\/f2be4e4423d78d9d97bf1e9a8db9fd48"},"description":"Endlich wieder gr\u00fcne Kurse auf der Handelsplattform: Der DAX zieht am Freitagmittag kr\u00e4ftig an. Damit setzte er auf der Stabilisierung vom Vortag auf.","breadcrumb":{"@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#primaryimage","url":"https:\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg","contentUrl":"https:\/\/bernstein-bank.azureedge.net\/wp-content\/uploads\/2020\/02\/trading-pen.jpg","width":800,"height":455,"caption":"Trading pen"},{"@type":"BreadcrumbList","@id":"https:\/\/bernstein-bank.com\/en\/dax-recaptures-the-9000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bernstein-bank.com\/de\/"},{"@type":"ListItem","position":2,"name":"DAX erobert die 9.000 zur\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/bernstein-bank.com\/en\/#website","url":"https:\/\/bernstein-bank.com\/en\/","name":"Bernstein Bank","description":"Bernstein Bank","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bernstein-bank.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/bernstein-bank.com\/en\/#\/schema\/person\/f2be4e4423d78d9d97bf1e9a8db9fd48","name":"Wordpress Support"}]}},"_links":{"self":[{"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/posts\/15452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/comments?post=15452"}],"version-history":[{"count":0,"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/posts\/15452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/media\/14722"}],"wp:attachment":[{"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/media?parent=15452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/categories?post=15452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bernstein-bank.com\/de\/wp-json\/wp\/v2\/tags?post=15452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}